{"id":4016,"date":"2025-06-26T10:21:47","date_gmt":"2025-06-26T08:21:47","guid":{"rendered":"https:\/\/vskultur.de\/?post_type=projekte&#038;p=4016"},"modified":"2025-06-26T10:21:48","modified_gmt":"2025-06-26T08:21:48","slug":"tamar-reseck-seminare-und-coaching","status":"publish","type":"projekte","link":"https:\/\/vskultur.de\/en\/projekte\/sport-gesundheit-lifestyle\/tamar-reseck-seminare-und-coaching\/","title":{"rendered":"Tamar Reseck - Seminare und Coaching"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Mein Name ist Dr. Tamar Reseck. Ich unterst\u00fctze Menschen dabei, innere Hemmnisse, \u00c4ngste und blockierende Selbstbilder zu \u00fcberwinden, damit sie mit Freude, Selbstvertrauen und Souver\u00e4nit\u00e4t vor anderen sprechen k\u00f6nnen \u2013 auch spontan. Im Mittelpunkt stehen nicht Techniken, sondern die pers\u00f6nliche Entwicklung. Ich biete Einzelcoachings, Gruppensettings, Workshops und Seminare an, die Raum f\u00fcr Reflexion, Wachstum und authentische Kommunikation schaffen. Erg\u00e4nzt wird mein Angebot durch inspirierende Vortr\u00e4ge zu verschiedenen Themen der Pers\u00f6nlichkeitsentwicklung, die Impulse geben und zum Nachdenken anregen.<\/p>","protected":false},"excerpt":{"rendered":"<p>Mein Name ist Dr. Tamar Reseck. Ich unterst\u00fctze Menschen dabei, innere Hemmnisse, \u00c4ngste und blockierende Selbstbilder zu \u00fcberwinden, damit sie mit Freude, Selbstvertrauen und Souver\u00e4nit\u00e4t vor anderen sprechen k\u00f6nnen \u2013 auch spontan. Im Mittelpunkt stehen nicht Techniken, sondern die pers\u00f6nliche Entwicklung. Ich biete Einzelcoachings, Gruppensettings, Workshops und Seminare an, die Raum f\u00fcr Reflexion, Wachstum und [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":4017,"parent":0,"template":"","cluster":[33],"class_list":["post-4016","projekte","type-projekte","status-publish","has-post-thumbnail","hentry","cluster-sport-gesundheit-lifestyle"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tamar Reseck - Seminare und Coaching - Visionskultur<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vskultur.de\/en\/projekte\/sport-gesundheit-lifestyle\/tamar-reseck-seminare-und-coaching\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tamar Reseck - Seminare und Coaching - Visionskultur\" \/>\n<meta property=\"og:description\" content=\"Mein Name ist Dr. Tamar Reseck. Ich unterst\u00fctze Menschen dabei, innere Hemmnisse, \u00c4ngste und blockierende Selbstbilder zu \u00fcberwinden, damit sie mit Freude, Selbstvertrauen und Souver\u00e4nit\u00e4t vor anderen sprechen k\u00f6nnen \u2013 auch spontan. Im Mittelpunkt stehen nicht Techniken, sondern die pers\u00f6nliche Entwicklung. Ich biete Einzelcoachings, Gruppensettings, Workshops und Seminare an, die Raum f\u00fcr Reflexion, Wachstum und [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vskultur.de\/en\/projekte\/sport-gesundheit-lifestyle\/tamar-reseck-seminare-und-coaching\/\" \/>\n<meta property=\"og:site_name\" content=\"Visionskultur\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-26T08:21:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vskultur.de\/wp-content\/uploads\/2025\/06\/Tamar-Reseck.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1738\" \/>\n\t<meta property=\"og:image:height\" content=\"1912\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vskultur.de\\\/projekte\\\/sport-gesundheit-lifestyle\\\/tamar-reseck-seminare-und-coaching\\\/\",\"url\":\"https:\\\/\\\/vskultur.de\\\/projekte\\\/sport-gesundheit-lifestyle\\\/tamar-reseck-seminare-und-coaching\\\/\",\"name\":\"Tamar Reseck - Seminare und Coaching - Visionskultur\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vskultur.de\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vskultur.de\\\/projekte\\\/sport-gesundheit-lifestyle\\\/tamar-reseck-seminare-und-coaching\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vskultur.de\\\/projekte\\\/sport-gesundheit-lifestyle\\\/tamar-reseck-seminare-und-coaching\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vskultur.de\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Tamar-Reseck.jpeg\",\"datePublished\":\"2025-06-26T08:21:47+00:00\",\"dateModified\":\"2025-06-26T08:21:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vskultur.de\\\/projekte\\\/sport-gesundheit-lifestyle\\\/tamar-reseck-seminare-und-coaching\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vskultur.de\\\/projekte\\\/sport-gesundheit-lifestyle\\\/tamar-reseck-seminare-und-coaching\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/vskultur.de\\\/projekte\\\/sport-gesundheit-lifestyle\\\/tamar-reseck-seminare-und-coaching\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vskultur.de\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Tamar-Reseck.jpeg\",\"contentUrl\":\"https:\\\/\\\/vskultur.de\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Tamar-Reseck.jpeg\",\"width\":1738,\"height\":1912},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vskultur.de\\\/projekte\\\/sport-gesundheit-lifestyle\\\/tamar-reseck-seminare-und-coaching\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/vskultur.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projekte\",\"item\":\"https:\\\/\\\/vskultur.de\\\/projekte\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tamar Reseck - Seminare und Coaching\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vskultur.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/vskultur.de\\\/en\\\/\",\"name\":\"Visionskultur\",\"description\":\"Ideenf\u00f6rderung und Standortentwicklung Bremen\",\"publisher\":{\"@id\":\"https:\\\/\\\/vskultur.de\\\/en\\\/#organization\"},\"alternateName\":\"Creative Hub Bremen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vskultur.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vskultur.de\\\/en\\\/#organization\",\"name\":\"Visionskultur\",\"url\":\"https:\\\/\\\/vskultur.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/vskultur.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vskultur.de\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Logo_Visionskultur.jpg\",\"contentUrl\":\"https:\\\/\\\/vskultur.de\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Logo_Visionskultur.jpg\",\"width\":477,\"height\":476,\"caption\":\"Visionskultur\"},\"image\":{\"@id\":\"https:\\\/\\\/vskultur.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tamar Reseck - Seminare und Coaching - Visionskultur","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vskultur.de\/en\/projekte\/sport-gesundheit-lifestyle\/tamar-reseck-seminare-und-coaching\/","og_locale":"en_GB","og_type":"article","og_title":"Tamar Reseck - Seminare und Coaching - Visionskultur","og_description":"Mein Name ist Dr. Tamar Reseck. Ich unterst\u00fctze Menschen dabei, innere Hemmnisse, \u00c4ngste und blockierende Selbstbilder zu \u00fcberwinden, damit sie mit Freude, Selbstvertrauen und Souver\u00e4nit\u00e4t vor anderen sprechen k\u00f6nnen \u2013 auch spontan. Im Mittelpunkt stehen nicht Techniken, sondern die pers\u00f6nliche Entwicklung. Ich biete Einzelcoachings, Gruppensettings, Workshops und Seminare an, die Raum f\u00fcr Reflexion, Wachstum und [&hellip;]","og_url":"https:\/\/vskultur.de\/en\/projekte\/sport-gesundheit-lifestyle\/tamar-reseck-seminare-und-coaching\/","og_site_name":"Visionskultur","article_modified_time":"2025-06-26T08:21:48+00:00","og_image":[{"width":1738,"height":1912,"url":"https:\/\/vskultur.de\/wp-content\/uploads\/2025\/06\/Tamar-Reseck.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/vskultur.de\/projekte\/sport-gesundheit-lifestyle\/tamar-reseck-seminare-und-coaching\/","url":"https:\/\/vskultur.de\/projekte\/sport-gesundheit-lifestyle\/tamar-reseck-seminare-und-coaching\/","name":"Tamar Reseck - Seminare und Coaching - Visionskultur","isPartOf":{"@id":"https:\/\/vskultur.de\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vskultur.de\/projekte\/sport-gesundheit-lifestyle\/tamar-reseck-seminare-und-coaching\/#primaryimage"},"image":{"@id":"https:\/\/vskultur.de\/projekte\/sport-gesundheit-lifestyle\/tamar-reseck-seminare-und-coaching\/#primaryimage"},"thumbnailUrl":"https:\/\/vskultur.de\/wp-content\/uploads\/2025\/06\/Tamar-Reseck.jpeg","datePublished":"2025-06-26T08:21:47+00:00","dateModified":"2025-06-26T08:21:48+00:00","breadcrumb":{"@id":"https:\/\/vskultur.de\/projekte\/sport-gesundheit-lifestyle\/tamar-reseck-seminare-und-coaching\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vskultur.de\/projekte\/sport-gesundheit-lifestyle\/tamar-reseck-seminare-und-coaching\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/vskultur.de\/projekte\/sport-gesundheit-lifestyle\/tamar-reseck-seminare-und-coaching\/#primaryimage","url":"https:\/\/vskultur.de\/wp-content\/uploads\/2025\/06\/Tamar-Reseck.jpeg","contentUrl":"https:\/\/vskultur.de\/wp-content\/uploads\/2025\/06\/Tamar-Reseck.jpeg","width":1738,"height":1912},{"@type":"BreadcrumbList","@id":"https:\/\/vskultur.de\/projekte\/sport-gesundheit-lifestyle\/tamar-reseck-seminare-und-coaching\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/vskultur.de\/"},{"@type":"ListItem","position":2,"name":"Projekte","item":"https:\/\/vskultur.de\/projekte\/"},{"@type":"ListItem","position":3,"name":"Tamar Reseck - Seminare und Coaching"}]},{"@type":"WebSite","@id":"https:\/\/vskultur.de\/en\/#website","url":"https:\/\/vskultur.de\/en\/","name":"Vision culture","description":"Ideenf\u00f6rderung und Standortentwicklung Bremen","publisher":{"@id":"https:\/\/vskultur.de\/en\/#organization"},"alternateName":"Creative Hub Bremen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vskultur.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/vskultur.de\/en\/#organization","name":"Vision culture","url":"https:\/\/vskultur.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/vskultur.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/vskultur.de\/wp-content\/uploads\/2026\/07\/Logo_Visionskultur.jpg","contentUrl":"https:\/\/vskultur.de\/wp-content\/uploads\/2026\/07\/Logo_Visionskultur.jpg","width":477,"height":476,"caption":"Visionskultur"},"image":{"@id":"https:\/\/vskultur.de\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/vskultur.de\/en\/wp-json\/wp\/v2\/projekte\/4016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vskultur.de\/en\/wp-json\/wp\/v2\/projekte"}],"about":[{"href":"https:\/\/vskultur.de\/en\/wp-json\/wp\/v2\/types\/projekte"}],"author":[{"embeddable":true,"href":"https:\/\/vskultur.de\/en\/wp-json\/wp\/v2\/users\/10"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vskultur.de\/en\/wp-json\/wp\/v2\/media\/4017"}],"wp:attachment":[{"href":"https:\/\/vskultur.de\/en\/wp-json\/wp\/v2\/media?parent=4016"}],"wp:term":[{"taxonomy":"cluster","embeddable":true,"href":"https:\/\/vskultur.de\/en\/wp-json\/wp\/v2\/cluster?post=4016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}