{"id":28,"count":27,"description":"Bremen hat eine lange Tradition der Weltoffenheit, der Emanzipation und Solidarit\u00e4t. Darauf aufbauend bringen neue Projekte und Akteure soziale Innovationen und Bildungsangebote in die bestehende Bildungs- und Soziallandschaft ein. Sie tragen dazu bei, neue Herausforderungen anzugehen und Generationen fu\u0308r die Zukunft zu wappnen. Wir begleiten und f\u00f6rdern Initiativen, Menschen mit neuen Ideen und Gru\u0308ndungsvorhaben\r\ndabei, ihre Projekte nachhaltig umzusetzen. Ob allein, in Kooperation mit\r\nGeleichgesinnten oder zusammen mit etablierten Akteuren am Standort.","link":"https:\/\/vskultur.de\/en\/projekte\/cluster\/bildung-soziales\/","name":"Education &amp; Social Affairs","slug":"bildung-soziales","taxonomy":"cluster","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/vskultur.de\/en\/wp-json\/wp\/v2\/cluster\/28","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vskultur.de\/en\/wp-json\/wp\/v2\/cluster"}],"about":[{"href":"https:\/\/vskultur.de\/en\/wp-json\/wp\/v2\/taxonomies\/cluster"}],"wp:post_type":[{"href":"https:\/\/vskultur.de\/en\/wp-json\/wp\/v2\/projekte?cluster=28"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}